{"id":625,"date":"2013-05-18T10:18:00","date_gmt":"2013-06-18T10:18:00","guid":{"rendered":"http:\/\/www.blog-sejour-linguistique.fr\/sejours-linguistiques\/?p=625"},"modified":"2009-02-27T09:46:08","modified_gmt":"2009-02-27T09:46:08","slug":"angleterre-shane-global-3","status":"publish","type":"post","link":"http:\/\/www.blog-sejour-linguistique.fr\/sejours-linguistiques\/2013\/05\/18\/angleterre-shane-global-3\/","title":{"rendered":"Angleterre &#8211; Shane Global"},"content":{"rendered":"<blockquote><p><a href=\"http:\/\/www.activa-langues.com\/fr\/sejour-linguistique-en-angleterre\/londres\/\" target=\"_blank\">Mon s\u00e9jour linguistique \u00e0 Londres<\/a> s&rsquo;est tr\u00e8s bien pass\u00e9. Les cours \u00e9taient vivants et interactifs et bien que mon s\u00e9jour fut court, je pense avoir progress\u00e9 en anglais. Les profs que j&rsquo;ai eu \u00e9taient bons et motiv\u00e9s. J&rsquo;ai appreci\u00e9 de rencontrer des \u00e9tudiants venant de tous les horizons et de pouvoir \u00e9changer avec eux m\u00eame si encore une fois un s\u00e9jour de une semaine est trop court pour tisser des liens amicaux. J&rsquo;\u00e9tais le plus \u00e2g\u00e9 du groupe mais en g\u00e9n\u00e9ral ces \u00e9tudiants qui font la d\u00e9marche de s\u00e9journer dans un pays \u00e9tranger pour en apprendre la langue ont un esprit assez ouvert.(&#8230;)<br \/>\nEn conclusion, ce s\u00e9jour m&rsquo;a donn\u00e9 envie de renouveler l&rsquo;exp\u00e9rience avec peut-\u00eatre un s\u00e9jour un peu plus long.<br \/>\nUn conseil : jaurais d\u00fb le faire plus t\u00f4t&#8230;<br \/>\nCordialement<\/p><\/blockquote>\n<p><span style=\"color: #e0027a;\"><em>Patrice &#8211; 53 ans &#8211; Profession : Medecin &#8211; Centre de cours : <a href=\"http:\/\/www.activa-langues.com\/fr\/sejour-linguistique-en-angleterre\/londres-mayfair\/shane-global\/\" target=\"_blank\">Shane Global<\/a><br \/>\n<\/em><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-626\" title=\"shane3\" src=\"http:\/\/www.blog-sejour-linguistique.fr\/sejours-linguistiques\/wp-content\/uploads\/2009\/02\/shane3.jpg\" alt=\"shane3\" width=\"630\" height=\"130\" srcset=\"http:\/\/www.blog-sejour-linguistique.fr\/sejours-linguistiques\/wp-content\/uploads\/2009\/02\/shane3.jpg 630w, http:\/\/www.blog-sejour-linguistique.fr\/sejours-linguistiques\/wp-content\/uploads\/2009\/02\/shane3-300x61.jpg 300w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Mon s\u00e9jour linguistique \u00e0 Londres s&rsquo;est tr\u00e8s bien pass\u00e9. Les cours \u00e9taient vivants et interactifs et bien que mon s\u00e9jour fut court, je pense avoir progress\u00e9 en anglais. Les profs que j&rsquo;ai eu \u00e9taient bons et motiv\u00e9s. J&rsquo;ai appreci\u00e9 de <a class=\"more-link\" href=\"http:\/\/www.blog-sejour-linguistique.fr\/sejours-linguistiques\/2013\/05\/18\/angleterre-shane-global-3\/\">Continuer la lecture <span class=\"screen-reader-text\">  Angleterre &#8211; Shane Global<\/span><span class=\"meta-nav\">&rarr;<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-625","post","type-post","status-publish","format-standard","hentry","category-vos-temoignages"],"_links":{"self":[{"href":"http:\/\/www.blog-sejour-linguistique.fr\/sejours-linguistiques\/wp-json\/wp\/v2\/posts\/625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.blog-sejour-linguistique.fr\/sejours-linguistiques\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.blog-sejour-linguistique.fr\/sejours-linguistiques\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.blog-sejour-linguistique.fr\/sejours-linguistiques\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.blog-sejour-linguistique.fr\/sejours-linguistiques\/wp-json\/wp\/v2\/comments?post=625"}],"version-history":[{"count":10,"href":"http:\/\/www.blog-sejour-linguistique.fr\/sejours-linguistiques\/wp-json\/wp\/v2\/posts\/625\/revisions"}],"predecessor-version":[{"id":768,"href":"http:\/\/www.blog-sejour-linguistique.fr\/sejours-linguistiques\/wp-json\/wp\/v2\/posts\/625\/revisions\/768"}],"wp:attachment":[{"href":"http:\/\/www.blog-sejour-linguistique.fr\/sejours-linguistiques\/wp-json\/wp\/v2\/media?parent=625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.blog-sejour-linguistique.fr\/sejours-linguistiques\/wp-json\/wp\/v2\/categories?post=625"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.blog-sejour-linguistique.fr\/sejours-linguistiques\/wp-json\/wp\/v2\/tags?post=625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}